{"id":29385,"date":"2025-11-01T17:32:21","date_gmt":"2025-11-01T23:32:21","guid":{"rendered":"https:\/\/globalhealthintelligence.com\/os-hospitais-mais-bem-equipados-da-colombia-em-2019\/"},"modified":"2025-12-20T11:46:52","modified_gmt":"2025-12-20T17:46:52","slug":"os-hospitais-mais-bem-equipados-da-colombia-em-2019","status":"publish","type":"page","link":"https:\/\/globalhealthintelligence.com\/pt-br\/os-hospitais-mais-bem-equipados-da-america-latina-em-2019\/os-hospitais-mais-bem-equipados-da-colombia-em-2019\/","title":{"rendered":"Os hospitais mais bem equipados da Col\u00f4mbia em 2019"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;28964&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; column_margin_custom=&#8221;7%&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;30px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;]\n<h3>Hospitais con mais bem equipados para a acomoda\u00e7\u00e3o de pacientes<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;](n\u00famero total de leitos)[\/nectar_responsive_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table width=\"100%\">\n<thead><\/thead>\n<tbody>\n<tr>\n<td>1<\/td>\n<td style=\"text-align: left;\">HOSPITAL GENERAL DE MEDELL\u00cdN LUZ CASTRO DE GUTI\u00c9RREZ E.S.E.<\/td>\n<td style=\"text-align: right;\">652<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td style=\"text-align: left;\">IPS UNIVERSITARIA SEDE CL\u00cdNICA LE\u00d3N XIII<\/td>\n<td style=\"text-align: right;\">618<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N VALLE DEL LILI \u2013 SEDE BETANIA<\/td>\n<td style=\"text-align: right;\">510<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N SANTA FE DE BOGOT\u00c1<\/td>\n<td style=\"text-align: right;\">462<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td style=\"text-align: left;\">HOSPITAL DEPARTAMENTAL DE VILLAVICENCIO<\/td>\n<td style=\"text-align: right;\">448<\/td>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td style=\"text-align: left;\">ORGANIZACI\u00d3N CL\u00cdNICA GENERAL DEL NORTE S.A.<\/td>\n<td style=\"text-align: right;\">432<\/td>\n<\/tr>\n<tr>\n<td>7<\/td>\n<td style=\"text-align: left;\">HOSPITAL UNIVERSITARIO DEL VALLE EVARISTO GARC\u00cdA<\/td>\n<td style=\"text-align: right;\">419<\/td>\n<\/tr>\n<tr>\n<td>8<\/td>\n<td style=\"text-align: left;\">HOSPITAL PABLO TOB\u00d3N URIBE<\/td>\n<td style=\"text-align: right;\">410<\/td>\n<\/tr>\n<tr>\n<td>9<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N HOSPITAL PEDI\u00c1TRICO DE LA MISERICORDIA<\/td>\n<td style=\"text-align: right;\">380<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td style=\"text-align: left;\">HOSPITAL UNIVERSITARIO ERASMO MEOZ<\/td>\n<td style=\"text-align: right;\">378<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; column_margin_custom=&#8221;7%&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;30px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;]\n<h3>Hospitais con melhor infraestrutura para acomodar um alto volume de procedimentos<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;](salas cir\u00fargicas gerais)[\/nectar_responsive_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table width=\"100%\">\n<thead><\/thead>\n<tbody>\n<tr>\n<td>1<\/td>\n<td style=\"text-align: left;\">HOSPITAL UNIVERSITARIO DEL VALLE EVARISTO GARC\u00cdA E.S.E.<\/td>\n<td style=\"text-align: right;\">19<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA MEDELL\u00cdN, SEDE OCCIDENTE<\/td>\n<td style=\"text-align: right;\">18<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td style=\"text-align: left;\">HOSPITAL MILITAR CENTRAL<\/td>\n<td style=\"text-align: right;\">15<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA LAS AM\u00c9RICAS S.A.<\/td>\n<td style=\"text-align: right;\">15<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA FOSCAL<\/td>\n<td style=\"text-align: right;\">15<\/td>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N HOSPITALARIA SAN VICENTE DE PAUL<\/td>\n<td style=\"text-align: right;\">15<\/td>\n<\/tr>\n<tr>\n<td>7<\/td>\n<td style=\"text-align: left;\">SOCIEDAD DE CIRUG\u00cdA DE BOGOT\u00c1 HOSPITAL DE SAN JOS\u00c9<\/td>\n<td style=\"text-align: right;\">15<\/td>\n<\/tr>\n<tr>\n<td>8<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA DEL COUNTRY<\/td>\n<td style=\"text-align: right;\">15<\/td>\n<\/tr>\n<tr>\n<td>9<\/td>\n<td style=\"text-align: left;\">CENTRO M\u00c9DICO IMBANACO<\/td>\n<td style=\"text-align: right;\">14<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td style=\"text-align: left;\">HOSPITAL UNIVERSITARIO MAYOR M\u00c9DERI<\/td>\n<td style=\"text-align: right;\">14<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; column_margin_custom=&#8221;7%&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;30px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;]\n<h3>Hospitais con maior n\u00famero de equipamentos cir\u00fargicos<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;](n\u00famero total de equipamentos cir\u00fargicos)[\/nectar_responsive_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table width=\"100%\">\n<thead><\/thead>\n<tbody>\n<tr>\n<td>1<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N HOSPITALARIA SAN VICENTE DE PAUL<\/td>\n<td style=\"text-align: right;\">198<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td style=\"text-align: left;\">HOSPITAL EL TUNAL III NIVEL E.S.E.<\/td>\n<td style=\"text-align: right;\">159<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N CARDIOVASCULAR DE COLOMBIA<\/td>\n<td style=\"text-align: right;\">139<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N VALLE DEL LILI \u2013 SEDE BETANIA<\/td>\n<td style=\"text-align: right;\">139<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N SANTA FE DE BOGOT\u00c1<\/td>\n<td style=\"text-align: right;\">100<\/td>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA DEL PRADO<\/td>\n<td style=\"text-align: right;\">95<\/td>\n<\/tr>\n<tr>\n<td>7<\/td>\n<td style=\"text-align: left;\">HOSPITAL DEPARTAMENTAL DE VILLAVICENCIO<\/td>\n<td style=\"text-align: right;\">88<\/td>\n<\/tr>\n<tr>\n<td>8<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA REINA CATALINA<\/td>\n<td style=\"text-align: right;\">82<\/td>\n<\/tr>\n<tr>\n<td>9<\/td>\n<td style=\"text-align: left;\">HOSPITAL UNIVERSITARIO DE LA SAMARITANA<\/td>\n<td style=\"text-align: right;\">71<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td style=\"text-align: left;\">HOSPITAL UNIVERSITARIO MAYOR M\u00c9DERI<\/td>\n<td style=\"text-align: right;\">70<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; column_margin_custom=&#8221;7%&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;30px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;]\n<h3>Hospitais con maior foco em sa\u00fade cardiovascular<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;](n\u00famero total de equipamentos dedicados \u00e0 sa\u00fade cardiovascular)[\/nectar_responsive_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table width=\"100%\">\n<thead><\/thead>\n<tbody>\n<tr>\n<td>1<\/td>\n<td style=\"text-align: left;\">HOSPITAL SAN VICENTE FUNDACI\u00d3N<\/td>\n<td style=\"text-align: right;\">59<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td style=\"text-align: left;\">HOSPITAL UNIVERSITARIO MAYOR M\u00c9DERI<\/td>\n<td style=\"text-align: right;\">27<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td style=\"text-align: left;\">HOSPITAL UNIVERSITARIO DE LA SAMARITANA E.S.E.<\/td>\n<td style=\"text-align: right;\">26<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA REINA CATALINA<\/td>\n<td style=\"text-align: right;\">23<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td style=\"text-align: left;\">HOSPITAL UNIVERSITARIO DE SANTANDER<\/td>\n<td style=\"text-align: right;\">22<\/td>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td style=\"text-align: left;\">HOSPITAL MANUEL URIBE \u00c1NGEL<\/td>\n<td style=\"text-align: right;\">21<\/td>\n<\/tr>\n<tr>\n<td>7<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N VALLE DEL LILI \u2013 SEDE BETANIA<\/td>\n<td style=\"text-align: right;\">21<\/td>\n<\/tr>\n<tr>\n<td>8<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA CES CORPORACI\u00d3N PARA ESTUDIOS<\/td>\n<td style=\"text-align: right;\">19<\/td>\n<\/tr>\n<tr>\n<td>9<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA UNIVERSITARIA BOLIVARIANA<\/td>\n<td style=\"text-align: right;\">17<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA LAS AM\u00c9RICAS S.A.<\/td>\n<td style=\"text-align: right;\">17<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; column_margin_custom=&#8221;7%&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;30px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;]\n<h3>Hospitais con melhor base instalada para tratamento de c\u00e2ncer<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;](n\u00famero total de equipamentos oncol\u00f3gicos)[\/nectar_responsive_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table width=\"100%\">\n<thead><\/thead>\n<tbody>\n<tr>\n<td>1<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA EL ROSARIO SEDE EL TESORO<\/td>\n<td style=\"text-align: right;\">8<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N VALLE DEL LILI \u2013 SEDE BETANIA<\/td>\n<td style=\"text-align: right;\">7<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N HOSPITALARIA SAN VICENTE DE PAUL<\/td>\n<td style=\"text-align: right;\">5<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td style=\"text-align: left;\">HOSPITAL EL TUNAL III NIVEL E.S.E.<\/td>\n<td style=\"text-align: right;\">5<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N SANTA FE DE BOGOT\u00c1<\/td>\n<td style=\"text-align: right;\">4<\/td>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA LAS AM\u00c9RICAS S.A.<\/td>\n<td style=\"text-align: right;\">4<\/td>\n<\/tr>\n<tr>\n<td>7<\/td>\n<td style=\"text-align: left;\">IMAT ONCOM\u00c9DICA S.A.<\/td>\n<td style=\"text-align: right;\">4<\/td>\n<\/tr>\n<tr>\n<td>8<\/td>\n<td style=\"text-align: left;\">HOSPITAL GENERAL DE MEDELL\u00cdN LUZ CASTRO DE GUTI\u00c9RREZ<\/td>\n<td style=\"text-align: right;\">4<\/td>\n<\/tr>\n<tr>\n<td>9<\/td>\n<td style=\"text-align: left;\">HOSPITAL DEPARTAMENTAL DE VILLAVICENCIO<\/td>\n<td style=\"text-align: right;\">3<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td style=\"text-align: left;\">HOSPITAL UNIVERSITARIO DE LA SAMARITANA<\/td>\n<td style=\"text-align: right;\">3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; column_margin_custom=&#8221;7%&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;30px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;]\n<h3>Hospitais con maior n\u00famero de equipamentos de diagn\u00f3stico por imagem<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;](n\u00famero total de equipamentos diagn\u00f3sticos)[\/nectar_responsive_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table width=\"100%\">\n<thead><\/thead>\n<tbody>\n<tr>\n<td>1<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N SANTA FE DE BOGOT\u00c1<\/td>\n<td style=\"text-align: right;\">25<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N VALLE DEL LILI \u2013 SEDE BETANIA<\/td>\n<td style=\"text-align: right;\">22<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA UNIVERSITARIA BOLIVARIANA<\/td>\n<td style=\"text-align: right;\">17<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA LAS AM\u00c9RICAS<\/td>\n<td style=\"text-align: right;\">15<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td style=\"text-align: left;\">DIME CL\u00cdNICA NEUROCARDIOVASCULAR S.A.<\/td>\n<td style=\"text-align: right;\">15<\/td>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td style=\"text-align: left;\">CENTRO DE ALTA ESPECIALIDAD CIUDAD BLANCA<\/td>\n<td style=\"text-align: right;\">12<\/td>\n<\/tr>\n<tr>\n<td>7<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA DE LA MUJER<\/td>\n<td style=\"text-align: right;\">12<\/td>\n<\/tr>\n<tr>\n<td>8<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA REY DAVID<\/td>\n<td style=\"text-align: right;\">12<\/td>\n<\/tr>\n<tr>\n<td>9<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA PORTOAZUL S.A.<\/td>\n<td style=\"text-align: right;\">11<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td style=\"text-align: left;\">SERVICIOS ESPECIALES DE SALUD<\/td>\n<td style=\"text-align: right;\">10<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;custom&#8221; column_margin_custom=&#8221;7%&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;30px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; sticky_content=&#8221;true&#8221; sticky_content_functionality=&#8221;css&#8221; sticky_content_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;]\n<h3>Os melhores hospitais para acomodar rec\u00e9m-nascidos<\/h3>\n[\/nectar_responsive_text][nectar_responsive_text inherited_font_style=&#8221;default&#8221; font_size_max=&#8221;90px&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243;](n\u00famero total de equipamentos para maternidade)[\/nectar_responsive_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;none&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<table width=\"100%\">\n<thead><\/thead>\n<tbody>\n<tr>\n<td>1<\/td>\n<td style=\"text-align: left;\">HOSPITAL LA VICTORIA SEDE MATERNO INFANTIL<\/td>\n<td style=\"text-align: right;\">112<\/td>\n<\/tr>\n<tr>\n<td>2<\/td>\n<td style=\"text-align: left;\">HOSPITAL INTERNACIONAL DE COLOMBIA &#8211; F. CARDIOVASCULAR DE COLOMBIA<\/td>\n<td style=\"text-align: right;\">100<\/td>\n<\/tr>\n<tr>\n<td>3<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA UNIVERSITARIA BOLIVARIANA<\/td>\n<td style=\"text-align: right;\">88<\/td>\n<\/tr>\n<tr>\n<td>4<\/td>\n<td style=\"text-align: left;\">CL\u00cdNICA DEL PRADO<\/td>\n<td style=\"text-align: right;\">88<\/td>\n<\/tr>\n<tr>\n<td>5<\/td>\n<td style=\"text-align: left;\">HOSPITAL GENERAL DE MEDELL\u00cdN LUZ CASTRO DE GUTI\u00c9RREZ E.S.E.<\/td>\n<td style=\"text-align: right;\">78<\/td>\n<\/tr>\n<tr>\n<td>6<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N VALLE DEL LILI \u2013 SEDE BETANIA<\/td>\n<td style=\"text-align: right;\">76<\/td>\n<\/tr>\n<tr>\n<td>7<\/td>\n<td style=\"text-align: left;\">HOSPITAL UNIVERSITARIO SAN JOS\u00c9 DE POPAY\u00c1N<\/td>\n<td style=\"text-align: right;\">66<\/td>\n<\/tr>\n<tr>\n<td>8<\/td>\n<td style=\"text-align: left;\">FUNDACI\u00d3N SANTA FE DE BOGOT\u00c1<\/td>\n<td style=\"text-align: right;\">66<\/td>\n<\/tr>\n<tr>\n<td>9<\/td>\n<td style=\"text-align: left;\">HOSPITAL NI\u00d1O JES\u00daS DE BARRANQUILLA E.S.E.<\/td>\n<td style=\"text-align: right;\">64<\/td>\n<\/tr>\n<tr>\n<td>10<\/td>\n<td style=\"text-align: left;\">HOSPITAL PABLO TOB\u00d3N URIBE<\/td>\n<td style=\"text-align: right;\">64<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;500&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#14B8A6&#8243; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;258&#8243;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":29557,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":3,"footnotes":""},"class_list":["post-29385","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/globalhealthintelligence.com\/pt-br\/wp-json\/wp\/v2\/pages\/29385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalhealthintelligence.com\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/globalhealthintelligence.com\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/globalhealthintelligence.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/globalhealthintelligence.com\/pt-br\/wp-json\/wp\/v2\/comments?post=29385"}],"version-history":[{"count":1,"href":"https:\/\/globalhealthintelligence.com\/pt-br\/wp-json\/wp\/v2\/pages\/29385\/revisions"}],"predecessor-version":[{"id":29386,"href":"https:\/\/globalhealthintelligence.com\/pt-br\/wp-json\/wp\/v2\/pages\/29385\/revisions\/29386"}],"up":[{"embeddable":true,"href":"https:\/\/globalhealthintelligence.com\/pt-br\/wp-json\/wp\/v2\/pages\/29557"}],"wp:attachment":[{"href":"https:\/\/globalhealthintelligence.com\/pt-br\/wp-json\/wp\/v2\/media?parent=29385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}